{"id":1804,"date":"2026-05-12T11:14:55","date_gmt":"2026-05-12T09:14:55","guid":{"rendered":"https:\/\/www.ms-leibnitz.at\/?post_type=tribe_events&#038;p=1804"},"modified":"2026-05-12T11:14:56","modified_gmt":"2026-05-12T09:14:56","slug":"abschlusskonzert-florian-temmel-timo-ambros","status":"publish","type":"tribe_events","link":"https:\/\/www.ms-leibnitz.at\/index.php\/event\/abschlusskonzert-florian-temmel-timo-ambros\/","title":{"rendered":"Abschlusskonzert Florian Temmel &amp; Timo Ambros"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t27. Mai\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t @ \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t17:30\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &#8211; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t19:00\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"453\" src=\"https:\/\/www.ms-leibnitz.at\/wp-content\/uploads\/2026\/05\/Poster_Abschlusskonzert_Richter.jpg\" alt=\"\" class=\"wp-image-1805\" srcset=\"https:\/\/www.ms-leibnitz.at\/wp-content\/uploads\/2026\/05\/Poster_Abschlusskonzert_Richter.jpg 640w, https:\/\/www.ms-leibnitz.at\/wp-content\/uploads\/2026\/05\/Poster_Abschlusskonzert_Richter-300x212.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n\n<div  class=\"tribe-block tribe-block__venue tribe-clearfix tribe-block__venue--has-map\" >\n\t\n\t\n<div class=\"tribe-block__venue__meta\">\n\t<div class=\"tribe-block__venue__name\">\n\t\t<h3>Musikschule Leibnitz<\/h3>\n\t<\/div>\n\n\t\n\t\t\t\t\t\t<address class=\"tribe-block__venue__address\">\n\t\t\t\t<span class=\"tribe-address\">\n\n<span class=\"tribe-street-address\">Wagnastra\u00dfe 9<\/span>\n\t\n\t\t<br>\n\t\t<span class=\"tribe-locality\">Leibnitz<\/span><span class=\"tribe-delimiter\">,<\/span>\n\n\t<abbr class=\"tribe-region tribe-events-abbr\" title=\"Steiermark\">Steiermark<\/abbr>\n\n\t<span class=\"tribe-postal-code\">8430<\/span>\n\n\t<span class=\"tribe-country-name\">\u00d6sterreich<\/span>\n\n<\/span>\n\n\t\t\t\t\t\t\t\t\t<a class=\"tribe-events-gmap\" href=\"https:\/\/maps.google.com\/maps?f=q&#038;source=s_q&#038;hl=en&#038;geocode=&#038;q=Wagnastra%C3%9Fe+9+Leibnitz+Steiermark+8430+%C3%96sterreich\" title=\"Klicken, um Google Karte anzuzeigen\" target=\"_blank\" rel=\"noreferrer noopener\">Google Karte anzeigen<\/a>\t\t\t\t\t\t\t<\/address>\n\t\t\n\t\t\t\t\t<span class=\"tribe-block__venue__phone\">03452 82601<\/span><br \/>\n\t\t\n\t\t\t\t\t<span class=\"tribe-block__venue__website\"><a href=\"http:\/\/www.ms-leibnitz.at\" target=\"_self\" rel=\"external\">Veranstaltungsort-Website anzeigen<\/a><\/span><br \/>\n\t\t\t\n\t<\/div>\n\t\n<div class=\"tribe-block__venue__map\">\n\t\n<iframe loading=\"lazy\"\n  title=\"Iframe von Google Maps, der die Adresse von Musikschule Leibnitz anzeigt\"\n  aria-label=\"Karte des Veranstaltungsortes\"\n  width=\"310px\"\n  height=\"256px\"\n  frameborder=\"0\" style=\"border:0\"\n  src=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyDNsicAsP6-VuGtAb1O9riI3oc_NOb7IOU&#038;q=Wagnastra%C3%9Fe+9+Leibnitz+Steiermark+Steiermark+8430+%C3%96sterreich+&#038;zoom=10\" allowfullscreen>\n<\/iframe>\n<\/div>\n\n\t<\/div>\n\n\n\n\n\t<div  class=\"tribe-block tribe-block__events-link\" >\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 23 17\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text\"\n\t\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\t\t\t\taria-label=\"Zeige Links an um Veranstaltungen zu deinem Kalender hinzuzuf\u00fcgen\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tZum Kalender hinzuf\u00fcgen\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20260527T173000\/20260527T190000&#038;text=Abschlusskonzert%20Florian%20Temmel%20%26amp%3B%20Timo%20Ambros&#038;details=%3Cfigure+class%3D%22wp-block-image+size-full%22%3E%3Cimg+src%3D%22https%3A%2F%2Fwww.ms-leibnitz.at%2Fwp-content%2Fuploads%2F2026%2F05%2FPoster_Abschlusskonzert_Richter.jpg%22+alt%3D%22%22+class%3D%22wp-image-1805%22%2F%3E%3C%2Ffigure%3E&#038;location=Musikschule%20Leibnitz,%20Wagnastra\u00dfe%209,%20Leibnitz,%20Steiermark,%208430,%20\u00d6sterreich&#038;trp=false&#038;ctz=UTC+2&#038;sprop=website:https:\/\/www.ms-leibnitz.at\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tGoogle Kalender\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1805,"template":"","meta":{"ngg_post_thumbnail":0,"_EventAllDay":false,"_EventTimezone":"UTC+2","_EventStartDate":"2026-05-27 17:30:00","_EventEndDate":"2026-05-27 19:00:00","_EventStartDateUTC":"2026-05-27 14:30:00","_EventEndDateUTC":"2026-05-27 16:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyCode":"EUR","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":" @ ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[],"_EventVenueID":[1198],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[34,81],"tribe_events_cat":[41,24],"class_list":["post-1804","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-abschlusskonzert","tag-schlagwerk","tribe_events_cat-abschlusspruefung","tribe_events_cat-konzert","cat_abschlusspruefung","cat_konzert"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/www.ms-leibnitz.at\/index.php\/wp-json\/wp\/v2\/tribe_events\/1804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ms-leibnitz.at\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.ms-leibnitz.at\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.ms-leibnitz.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.ms-leibnitz.at\/index.php\/wp-json\/wp\/v2\/tribe_events\/1804\/revisions"}],"predecessor-version":[{"id":1806,"href":"https:\/\/www.ms-leibnitz.at\/index.php\/wp-json\/wp\/v2\/tribe_events\/1804\/revisions\/1806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ms-leibnitz.at\/index.php\/wp-json\/wp\/v2\/media\/1805"}],"wp:attachment":[{"href":"https:\/\/www.ms-leibnitz.at\/index.php\/wp-json\/wp\/v2\/media?parent=1804"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ms-leibnitz.at\/index.php\/wp-json\/wp\/v2\/tags?post=1804"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.ms-leibnitz.at\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=1804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}